{"id":13259,"date":"2023-11-30T10:53:04","date_gmt":"2023-11-30T03:53:04","guid":{"rendered":"https:\/\/www.douglas.co.th\/?page_id=13259"},"modified":"2026-04-11T10:11:14","modified_gmt":"2026-04-11T03:11:14","slug":"llb-hons-law-uclan-th","status":"publish","type":"page","link":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/","title":{"rendered":"L.L.B. (Hons) \u0e2a\u0e32\u0e02\u0e32 Law"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"13259\" class=\"elementor elementor-13259\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8839a74 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8839a74\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79dd0bc\" data-id=\"79dd0bc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cb2f587 elementor-widget elementor-widget-breadcrumbs\" data-id=\"cb2f587\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"breadcrumbs.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<p id=\"breadcrumbs\"><span><span><a href=\"https:\/\/www.douglas.co.th\/th\/\">Home<\/a><\/span><\/span><\/p>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1bc37a02 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1bc37a02\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7a598a43\" data-id=\"7a598a43\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6743d1c5 elementor-widget elementor-widget-heading\" data-id=\"6743d1c5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:25px\">L.L.B. (Hons) Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c<\/span><\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-5609116 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5609116\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-752009c\" data-id=\"752009c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce6751d elementor-widget elementor-widget-heading\" data-id=\"ce6751d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:23px\">\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-228ef803 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"228ef803\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-47792d26\" data-id=\"47792d26\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-770102f2 elementor-widget elementor-widget-spacer\" data-id=\"770102f2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4417796d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4417796d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7cc636e5\" data-id=\"7cc636e5\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d96b865 elementor-widget elementor-widget-text-editor\" data-id=\"d96b865\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"color: #000000;\">\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-7bf7153c\" data-id=\"7bf7153c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a5bd00f elementor-widget elementor-widget-text-editor\" data-id=\"3a5bd00f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">1 \u0e1b\u0e35<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f2e880a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f2e880a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-45f4efb0\" data-id=\"45f4efb0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-70144ca1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"70144ca1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-245e6944 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"245e6944\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-441246cc\" data-id=\"441246cc\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bf906f3 elementor-widget elementor-widget-text-editor\" data-id=\"1bf906f3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"color: #000000;\">\u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-10f23613\" data-id=\"10f23613\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a779f4d elementor-widget elementor-widget-text-editor\" data-id=\"a779f4d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 &amp; \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7727f798 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7727f798\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-503eee54\" data-id=\"503eee54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3ab14748 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3ab14748\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-58179b9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"58179b9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6ce523ef\" data-id=\"6ce523ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-69eb1036 elementor-widget elementor-widget-text-editor\" data-id=\"69eb1036\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1fde0726\" data-id=\"1fde0726\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e72b4e4 elementor-widget elementor-widget-text-editor\" data-id=\"e72b4e4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 100%<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-434fdc63 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"434fdc63\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7b773e3c\" data-id=\"7b773e3c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d687c71 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"3d687c71\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fbde22 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fbde22\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-9268f5a\" data-id=\"9268f5a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-67281d1 elementor-widget elementor-widget-text-editor\" data-id=\"67281d1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>\u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-dfcf325\" data-id=\"dfcf325\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8a79486 elementor-widget elementor-widget-text-editor\" data-id=\"8a79486\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e27\u0e25\u0e32\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8720115 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8720115\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6f7d8cd\" data-id=\"6f7d8cd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f608323 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"f608323\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4f1c8ae7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4f1c8ae7\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-34a5c4ac\" data-id=\"34a5c4ac\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-faa0124 elementor-widget elementor-widget-text-editor\" data-id=\"faa0124\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><span style=\"caret-color: #000000;\"><b>Pathway to a Degree<\/b><\/span><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-6e9b6e98\" data-id=\"6e9b6e98\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-78beb9c2 elementor-widget elementor-widget-text-editor\" data-id=\"78beb9c2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">2 \u0e2a\u0e48\u0e27\u0e19<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2d8068b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2d8068b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-399bb6ce\" data-id=\"399bb6ce\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4f1d6bd8 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4f1d6bd8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a3f99a6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a3f99a6\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8f78d22\" data-id=\"8f78d22\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a2ec1f1 elementor-widget elementor-widget-text-editor\" data-id=\"a2ec1f1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>\u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c10313d\" data-id=\"c10313d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-007a56c elementor-widget elementor-widget-text-editor\" data-id=\"007a56c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e2a\u0e48\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3e98438e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3e98438e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-53d1dbb4\" data-id=\"53d1dbb4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f4a9cd7 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"7f4a9cd7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3434885e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3434885e\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-659a8515\" data-id=\"659a8515\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-76d42469 elementor-widget elementor-widget-text-editor\" data-id=\"76d42469\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>\u0e20\u0e32\u0e29\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19<\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-299c1c3a\" data-id=\"299c1c3a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-22b17296 elementor-widget elementor-widget-text-editor\" data-id=\"22b17296\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1c82b1b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1c82b1b4\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-17ad7a11\" data-id=\"17ad7a11\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c5a0a8c elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"4c5a0a8c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1a3fa5e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a3fa5e5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-271d5547\" data-id=\"271d5547\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33314285 elementor-button-danger elementor-mobile-align-center elementor-align-center elementor-tablet-align-center elementor-widget elementor-widget-button\" data-id=\"33314285\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#apply\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19!<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6e5a562 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6e5a562\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-638a6ef\" data-id=\"638a6ef\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7739e4f elementor-widget elementor-widget-spacer\" data-id=\"7739e4f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1f7fa454 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1f7fa454\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-588af96e\" data-id=\"588af96e\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-65874c0 elementor-widget elementor-widget-heading\" data-id=\"65874c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:25px\">\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-504e97a3 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"504e97a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8da0836 elementor-hidden-mobile elementor-widget elementor-widget-text-editor\" data-id=\"8da0836\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 (Hons) \u0e2a\u0e32\u0e02\u0e32 Law (top-up) \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c (Analytics) \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (International Business Law)<\/p><p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e1a \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 :<\/p><p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\"><strong>\u2022 <\/strong><\/span><\/span>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p><p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\"><strong>\u2022 <\/strong><\/span><\/span>\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17<\/p><p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\"><strong>\u2022 <\/strong><\/span><\/span>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e49\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e02\u0e19\u0e07 \u0e40\u0e0a\u0e48\u0e19<\/p><p style=\"padding-left: 40px;\"><span style=\"color: #000000;\"><span style=\"font-weight: 400;\"><strong>\u2022<\/strong> <\/span><\/span><strong>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u00a0<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u00a0<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32\u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e3f4f12 elementor-align-start elementor-hidden-mobile elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"e3f4f12\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.douglas.co.th\/th\/online-law-degree-uk-programs-th\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e14\u0e39\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-cc3c982 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"cc3c982\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 (Hons) \u0e2a\u0e32\u0e02\u0e32 Law (top-up) \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c (Analytics) \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (International Business Law)<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-091f47a elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"091f47a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e1a \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 :<\/p><p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\"><strong>\u2022 <\/strong><\/span><\/span>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28<\/p><p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\"><strong>\u2022 <\/strong><\/span><\/span>\u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17<\/p><p><span style=\"color: #000000;\"><span style=\"font-weight: 400;\"><strong>\u2022 <\/strong><\/span><\/span>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e49\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e02\u0e19\u0e07 \u0e40\u0e0a\u0e48\u0e19<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9df9d20 elementor-hidden-desktop elementor-hidden-tablet elementor-widget elementor-widget-text-editor\" data-id=\"9df9d20\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\"><span style=\"color: #000000;\"><span style=\"font-weight: 400;\"><strong>\u2022<\/strong> <\/span><\/span><strong>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1e\u0e32\u0e13\u0e34\u0e0a\u0e22\u0e4c\u00a0<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1a\u0e23\u0e34\u0e29\u0e31\u0e17<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e01\u0e32\u0e23\u0e04\u0e49\u0e32\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28\u00a0<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e17\u0e23\u0e31\u0e1e\u0e22\u0e4c\u0e2a\u0e34\u0e19\u0e17\u0e32\u0e07\u0e1b\u0e31\u0e0d\u0e0d\u0e32<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e1b\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e19\u0e2d\u0e32\u0e0a\u0e0d\u0e32\u0e01\u0e23\u0e23\u0e21\u0e17\u0e32\u0e07\u0e01\u0e32\u0e23\u0e40\u0e07\u0e34\u0e19<\/strong><\/p><p style=\"padding-left: 40px;\"><strong><span style=\"color: #000000;\">\u2022 <\/span>\u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e43\u0e19\u0e04\u0e49\u0e19\u0e04\u0e27\u0e49\u0e32\u0e2b\u0e32\u0e02\u0e49\u0e2d\u0e21\u0e39\u0e25 \u0e41\u0e25\u0e30\u0e40\u0e02\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e01\u0e21\u0e32\u0e43\u0e19\u0e40\u0e0a\u0e34\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e44\u0e14\u0e49\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e35\u0e1b\u0e23\u0e30\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e20\u0e32\u0e1e<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b9c3144 elementor-align-start elementor-hidden-desktop elementor-hidden-tablet elementor-icon-list--layout-traditional elementor-list-item-link-full_width elementor-widget elementor-widget-icon-list\" data-id=\"b9c3144\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"icon-list.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul class=\"elementor-icon-list-items\">\n\t\t\t\t\t\t\t<li class=\"elementor-icon-list-item\">\n\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.douglas.co.th\/th\/online-law-degree-uk-programs-th\/\">\n\n\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-icon\">\n\t\t\t\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-angle-double-right\"><\/i>\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-icon-list-text\">\u0e14\u0e39\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e37\u0e48\u0e19\u0e46<\/span>\n\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t<\/li>\n\t\t\t\t\t\t<\/ul>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-130b670b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"130b670b\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9a939ab\" data-id=\"9a939ab\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8c82d5b elementor-widget elementor-widget-heading\" data-id=\"8c82d5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:25px\">\u0e40\u0e07\u0e37\u0e48\u0e2d\u0e19\u0e44\u0e02\u0e01\u0e32\u0e23\u0e23\u0e31\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6b3fac1 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"6b3fac1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3612d896 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3612d896\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-59bcc4c9\" data-id=\"59bcc4c9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-657c85c8 elementor-widget-tablet__width-initial elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"657c85c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"768\" height=\"768\" src=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-online-uclan-1-768x768.webp\" class=\"attachment-medium_large size-medium_large wp-image-24375\" alt=\"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 llb hons law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e08\u0e32\u0e01 uclan\" srcset=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-online-uclan-1-768x768.webp 768w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-online-uclan-1-300x300.webp 300w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-online-uclan-1-150x150.webp 150w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-online-uclan-1-12x12.webp 12w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-online-uclan-1-50x50.webp 50w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-online-uclan-1-320x320.webp 320w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-online-uclan-1.webp 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-c80106a\" data-id=\"c80106a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8620e75 elementor-widget elementor-widget-text-editor\" data-id=\"8620e75\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>\u2022 <\/strong>Approved Centres are responsible for reviewing and making decisions as to the applicant\u2019s <\/span><span style=\"color: #000000;\">ability to complete the learning programme successfully and meet the demands of the qualification. The initial assessment by the centre, will need to consider the support that is readily available or can be made available to meet individual learner needs as appropriate.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ae2c12b elementor-widget elementor-widget-text-editor\" data-id=\"ae2c12b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>\u2022 <\/strong>Approved Centres are responsible for reviewing and making decisions as to the applicant\u2019s <\/span><span style=\"color: #000000;\">ability to complete the learning programme successfully and meet the demands of the qualification. <\/span><\/p><p><span style=\"color: #000000;\">The initial assessment by the centre, will need to consider the support that is readily available or can be made available to meet individual learner needs as appropriate.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f07dcec elementor-widget elementor-widget-text-editor\" data-id=\"f07dcec\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong>\u2022\u00a0<\/strong>The qualification has been designed to be accessible without artificial barriers that restrict access, for this qualification applicants must be aged 18 or over.<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-713169e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"713169e\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37f3b69\" data-id=\"37f3b69\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-83b8c98 elementor-widget elementor-widget-spacer\" data-id=\"83b8c98\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3cf4fde elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3cf4fde\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0746e41\" data-id=\"0746e41\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f2319f9 elementor-widget__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-html\" data-id=\"f2319f9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<a href=\"https:\/\/lin.ee\/lN5AfQb\"><img decoding=\"async\" src=\"https:\/\/scdn.line-apps.com\/n\/line_add_friends\/btn\/th.png\" alt=\"\u0e40\u0e1e\u0e34\u0e48\u0e21\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\" height=\"36\" border=\"0\"><\/a>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-68e887ae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"68e887ae\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<header class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-55b25548\" data-id=\"55b25548\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9a4f098 elementor-widget elementor-widget-heading\" data-id=\"9a4f098\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:25px\">\u0e27\u0e34\u0e0a\u0e32\u0e17\u0e35\u0e48\u0e08\u0e30\u0e44\u0e14\u0e49\u0e40\u0e23\u0e35\u0e22\u0e19<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-369b415 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"369b415\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/header>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-4488a009 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4488a009\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-1158139f\" data-id=\"1158139f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-37fd45f5 elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"37fd45f5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\">\u0e42\u0e1b\u0e23\u0e41\u0e01\u0e23\u0e21\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e2a\u0e32\u0e02\u0e32 Law (L.L.B.) \u0e08\u0e30\u0e1b\u0e23\u0e30\u0e01\u0e2d\u0e1a\u0e44\u0e1b\u0e14\u0e49\u0e27\u0e22 2 \u0e0a\u0e48\u0e27\u0e07\u0e43\u0e2b\u0e0d\u0e48\u0e46 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 :<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e059f19 elementor-widget elementor-widget-spacer\" data-id=\"e059f19\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b076887 elementor-widget elementor-widget-heading\" data-id=\"b076887\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"> <p style=\"font-size:18px\">\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 1 : Level 5 Extended Diploma in Law<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-497120f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"497120f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\"><span style=\"color: #000000;\">\u2022 Contract Law<br \/>\u2022 Criminal Law<br \/>\u2022 Legal Methods<br \/>\u2022 Public Law<br \/>\u2022 Equity and Trusts<br \/>\u2022 EU Law<br \/>\u2022 Land Law<br \/>\u2022 Law of Tort<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-64f733a elementor-widget elementor-widget-spacer\" data-id=\"64f733a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a29871a elementor-widget elementor-widget-heading\" data-id=\"a29871a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\"> <p style=\"font-size:18px\">\u0e2a\u0e48\u0e27\u0e19\u0e17\u0e35\u0e48 2 : Bachelor of Laws (LLB)<\/span><\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0aa5c5f elementor-widget__width-initial elementor-widget elementor-widget-text-editor\" data-id=\"0aa5c5f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"padding-left: 40px;\"><span style=\"color: #000000;\">\u2022 Alternate Dispute Resolution<br \/>\u2022 Graduate Professional Skill and Employability<br \/>\u2022 Law for Entrepreneurs<br \/>\u2022 International Humanitarian and Criminal Law<br \/>\u2022 Company Law<br \/>\u2022 Project<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-4b4ae836\" data-id=\"4b4ae836\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-31ac818a elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"31ac818a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"533\" height=\"800\" src=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-law-online-from-uclan-1.webp\" class=\"attachment-medium_large size-medium_large wp-image-24376\" alt=\"\" srcset=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-law-online-from-uclan-1.webp 533w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-law-online-from-uclan-1-200x300.webp 200w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/study-llb-hons-law-online-from-uclan-1-8x12.webp 8w\" sizes=\"(max-width: 533px) 100vw, 533px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a8d3ee2 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a8d3ee2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-acf079b\" data-id=\"acf079b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4be1e49 elementor-widget elementor-widget-spacer\" data-id=\"4be1e49\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-86ed82a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"86ed82a\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1ee0d1a1\" data-id=\"1ee0d1a1\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-160beed elementor-widget elementor-widget-heading\" data-id=\"160beed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:25px\">\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e19\u0e35\u0e49<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-540999d0 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"540999d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57fecfd elementor-widget elementor-widget-text-editor\" data-id=\"57fecfd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e21\u0e37\u0e48\u0e2d\u0e04\u0e38\u0e13\u0e40\u0e23\u0e35\u0e22\u0e19\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35 (\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21) \u0e2a\u0e32\u0e02\u0e32 Law (top-up) \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e2a\u0e34\u0e17\u0e18\u0e34\u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e1a\u0e23\u0e34\u0e01\u0e32\u0e23\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e08\u0e32\u0e01\u0e40\u0e23\u0e32 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-59fc9f6 elementor-widget elementor-widget-text-editor\" data-id=\"59fc9f6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"color: #000000;\"><strong><span style=\"color: #085398;\">\u2022 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e15\u0e31\u0e27\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 :<\/span><\/strong> \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e49\u0e2d\u0e19\u0e14\u0e39\u0e40\u0e19\u0e37\u0e49\u0e2d\u0e2b\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46, \u0e01\u0e23\u0e13\u0e35\u0e28\u0e36\u0e01\u0e29\u0e32 (case studies), \u0e2b\u0e23\u0e37\u0e2d\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19\u0e17\u0e35\u0e48\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e21\u0e2d\u0e1a\u0e2b\u0e21\u0e32\u0e22 \u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e02\u0e2d\u0e07\u0e40\u0e23\u0e32 (E-Learning Platform)<\/span><\/p><p><span style=\"color: #000000;\"><strong><span style=\"color: #085398;\">\u2022 \u0e01\u0e32\u0e23\u0e40\u0e02\u0e49\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (Webinars) :<\/span> <\/strong>\u0e40\u0e02\u0e49\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e41\u0e1a\u0e1a\u0e44\u0e25\u0e1f\u0e4c (live) \u0e2b\u0e23\u0e37\u0e2d \u0e14\u0e39\u0e22\u0e49\u0e2d\u0e19\u0e2b\u0e25\u0e31\u0e07 (recorded) \u0e08\u0e32\u0e01\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19\u0e17\u0e35\u0e48\u0e40\u0e0a\u0e35\u0e48\u0e22\u0e27\u0e0a\u0e32\u0e0d\u0e43\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e19\u0e31\u0e49\u0e19\u0e46<\/span><\/p><p><span style=\"color: #000000;\"><strong><span style=\"color: #085398;\">\u2022 \u0e15\u0e34\u0e27\u0e41\u0e1a\u0e1a\u0e15\u0e31\u0e27\u0e15\u0e48\u0e2d\u0e15\u0e31\u0e27\u0e01\u0e31\u0e1a\u0e15\u0e34\u0e27\u0e40\u0e15\u0e2d\u0e23\u0e4c : <\/span><\/strong>\u0e21\u0e35\u0e17\u0e35\u0e48\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32\u0e17\u0e35\u0e48\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e43\u0e19\u0e23\u0e32\u0e22\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2b\u0e23\u0e37\u0e2d \u0e41\u0e21\u0e49\u0e41\u0e15\u0e48\u0e15\u0e2d\u0e19\u0e17\u0e33\u0e27\u0e34\u0e17\u0e22\u0e32\u0e19\u0e34\u0e1e\u0e19\u0e18\u0e4c (dissertation)<\/span><\/p><p><span style=\"color: #000000;\"><strong><span style=\"color: #085398;\">\u2022 \u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07 E-Library :<\/span> <\/strong>\u0e40\u0e02\u0e49\u0e32\u0e16\u0e36\u0e07\u0e15\u0e33\u0e23\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e27\u0e34\u0e0a\u0e32\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e2b\u0e23\u0e37\u0e2d \u0e40\u0e25\u0e37\u0e2d\u0e01\u0e2d\u0e48\u0e32\u0e19\u0e2b\u0e19\u0e31\u0e07\u0e2a\u0e37\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e17\u0e35\u0e48\u0e1c\u0e39\u0e49\u0e2a\u0e2d\u0e19\u0e41\u0e19\u0e30\u0e19\u0e33\u0e43\u0e2b\u0e49\u0e2d\u0e48\u0e32\u0e19\u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e23\u0e35\u0e22\u0e19\u0e44\u0e14\u0e49\u0e15\u0e25\u0e2d\u0e14<\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-49faf7f0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"49faf7f0\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6a574841\" data-id=\"6a574841\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24ff991c elementor-widget__width-initial elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget elementor-widget-image\" data-id=\"24ff991c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/course-llb-hons-law-online-uclan-1-768x512.webp\" class=\"attachment-medium_large size-medium_large wp-image-24377\" alt=\"\" srcset=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/course-llb-hons-law-online-uclan-1-768x512.webp 768w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/course-llb-hons-law-online-uclan-1-300x200.webp 300w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/course-llb-hons-law-online-uclan-1-18x12.webp 18w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/course-llb-hons-law-online-uclan-1.webp 800w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-14e864e1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"14e864e1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-14447fc6\" data-id=\"14447fc6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0d66b6 elementor-widget elementor-widget-heading\" data-id=\"e0d66b6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:25px\">\u0e17\u0e33\u0e44\u0e21\u0e15\u0e49\u0e2d\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 (Hons) L.L.B. Law<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70321439 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"70321439\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d2ba2a elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d2ba2a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-270e2fa\" data-id=\"270e2fa\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f603d3e elementor-widget elementor-widget-text-editor\" data-id=\"f603d3e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1b.\u0e15\u0e23\u0e35 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e32\u0e02\u0e32 L.B.B. Law (top-up) \u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e \u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e19\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e07\u0e01\u0e32\u0e23\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e43\u0e08\u0e0a\u0e2d\u0e1a<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a29616f elementor-widget elementor-widget-text-editor\" data-id=\"a29616f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e1b.\u0e15\u0e23\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e02\u0e19\u0e07 \u0e40\u0e0a\u0e48\u0e19 Company Law, Law for Entrepreneurs, EU Law \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f39c91c elementor-widget elementor-widget-text-editor\" data-id=\"f39c91c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e27\u0e48\u0e32 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e08\u0e1a\u0e04\u0e2d\u0e23\u0e4c\u0e2a \u0e1b.\u0e15\u0e23\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32 \u0e04\u0e38\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e08\u0e23\u0e34\u0e07\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e2a\u0e48\u0e07\u0e15\u0e23\u0e07\u0e16\u0e36\u0e07\u0e1a\u0e49\u0e32\u0e19 \u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e41\u0e04\u0e25\u0e48\u0e27<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-585b2d2 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"585b2d2\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ac9032f\" data-id=\"ac9032f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4be470e elementor-widget elementor-widget-text-editor\" data-id=\"4be470e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e1b.\u0e15\u0e23\u0e35 \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e32\u0e02\u0e32 L.B.B. Law (top-up) \u0e16\u0e39\u0e01\u0e2d\u0e2d\u0e01\u0e41\u0e1a\u0e1a\u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e43\u0e2b\u0e49\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e25\u0e32\u0e22\u0e40\u0e1b\u0e47\u0e19\u0e19\u0e31\u0e01\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e21\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7d49127 elementor-widget elementor-widget-text-editor\" data-id=\"7d49127\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e44\u0e21\u0e48\u0e27\u0e48\u0e32\u0e08\u0e30\u0e40\u0e1b\u0e47\u0e19\u0e17\u0e19\u0e32\u0e22 \u0e2b\u0e23\u0e37\u0e2d\u0e2d\u0e32\u0e0a\u0e35\u0e1e\u0e2d\u0e37\u0e48\u0e19\u0e46 \u0e17\u0e35\u0e48\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e02\u0e49\u0e2d\u0e07\u0e01\u0e31\u0e1a\u0e27\u0e07\u0e01\u0e32\u0e23\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e25\u0e37\u0e2d\u0e01\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e14\u0e49\u0e15\u0e32\u0e21\u0e43\u0e08\u0e0a\u0e2d\u0e1a<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d83bc9 elementor-widget elementor-widget-text-editor\" data-id=\"5d83bc9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e2a\u0e34\u0e48\u0e07\u0e17\u0e35\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e08\u0e32\u0e01\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e1b.\u0e15\u0e23\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e19\u0e35\u0e49 \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e17\u0e33\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e2b\u0e25\u0e32\u0e01\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e02\u0e19\u0e07<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a67093 elementor-widget elementor-widget-text-editor\" data-id=\"9a67093\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e0a\u0e48\u0e19 Company Law, Law for Entrepreneurs, EU Law \u0e41\u0e25\u0e30\u0e2d\u0e35\u0e01\u0e21\u0e32\u0e01\u0e21\u0e32\u0e22<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85b1e40 elementor-widget elementor-widget-text-editor\" data-id=\"85b1e40\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e40\u0e23\u0e32\u0e40\u0e0a\u0e37\u0e48\u0e2d\u0e21\u0e31\u0e48\u0e19\u0e27\u0e48\u0e32 \u0e2b\u0e32\u0e01\u0e04\u0e38\u0e13\u0e08\u0e1a\u0e04\u0e2d\u0e23\u0e4c\u0e2a \u0e1b.\u0e15\u0e23\u0e35 \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e01\u0e31\u0e1a\u0e40\u0e23\u0e32 \u0e04\u0e38\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e08\u0e23\u0e34\u0e07\u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e2a\u0e48\u0e07\u0e15\u0e23\u0e07\u0e16\u0e36\u0e07\u0e1a\u0e49\u0e32\u0e19<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-62769e3 elementor-widget elementor-widget-text-editor\" data-id=\"62769e3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>\u0e23\u0e27\u0e21\u0e16\u0e36\u0e07\u0e04\u0e38\u0e13\u0e08\u0e30\u0e44\u0e14\u0e49\u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49 \u0e04\u0e27\u0e32\u0e21\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16 \u0e44\u0e1b\u0e43\u0e0a\u0e49\u0e43\u0e19\u0e07\u0e32\u0e19\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e43\u0e19\u0e2d\u0e19\u0e32\u0e04\u0e15\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e04\u0e25\u0e48\u0e2d\u0e07\u0e41\u0e04\u0e25\u0e48\u0e27<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f84edcc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f84edcc\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-face4d9\" data-id=\"face4d9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4d8c60 elementor-widget elementor-widget-spacer\" data-id=\"f4d8c60\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b2cc10d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b2cc10d\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-74a931f\" data-id=\"74a931f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-febfb67 elementor-widget elementor-widget-heading\" data-id=\"febfb67\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:25px\">\u0e15\u0e31\u0e27\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-c9fab58 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"c9fab58\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-79fd127\" data-id=\"79fd127\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-eb44884 elementor-widget__width-initial elementor-widget elementor-widget-image\" data-id=\"eb44884\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"745\" src=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/09\/sample-certificate-bsc-hons-llb-uclan.webp\" class=\"attachment-medium_large size-medium_large wp-image-32218\" alt=\"\" srcset=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/09\/sample-certificate-bsc-hons-llb-uclan.webp 500w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/09\/sample-certificate-bsc-hons-llb-uclan-201x300.webp 201w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/09\/sample-certificate-bsc-hons-llb-uclan-8x12.webp 8w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f053fca elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f053fca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b98747f\" data-id=\"b98747f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26ab58d elementor-widget elementor-widget-heading\" data-id=\"26ab58d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">\u0e14\u0e39\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e2d\u0e37\u0e48\u0e19\u0e46<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e415b7c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e415b7c\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-3492371\" data-id=\"3492371\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74b9854 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"74b9854\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.douglas.co.th\/th\/master-degree-th\/mba-online-courses-th\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">MBA<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-943359a\" data-id=\"943359a\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2cce419 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"2cce419\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e15\u0e23\u0e35<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-515e3bd\" data-id=\"515e3bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3b5df48 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"3b5df48\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.douglas.co.th\/th\/master-degree-th\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e42\u0e17<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-25 elementor-top-column elementor-element elementor-element-f2ff9f3\" data-id=\"f2ff9f3\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-143bbdb elementor-align-center elementor-widget elementor-widget-button\" data-id=\"143bbdb\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.douglas.co.th\/th\/dba-degree-th\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e40\u0e2d\u0e01<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-114dce1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"114dce1\" data-element_type=\"section\" data-e-type=\"section\" id=\"apply\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0a56667\" data-id=\"0a56667\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c88bc9a elementor-widget elementor-widget-spacer\" data-id=\"c88bc9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-78f8849 elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78f8849\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ea987a8\" data-id=\"ea987a8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-38d0415 elementor-widget elementor-widget-text-editor\" data-id=\"38d0415\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><strong><span style=\"color: #000000;\">\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e2b\u0e23\u0e37\u0e2d \u0e21\u0e35\u0e04\u0e33\u0e16\u0e32\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46<\/span><\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0baa29f elementor-widget elementor-widget-text-editor\" data-id=\"0baa29f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><span style=\"color: #000000;\">\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e21\u0e32\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e40\u0e23\u0e32 \u0e1f\u0e23\u0e35 \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e41\u0e25\u0e30\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<br \/><\/span><span style=\"color: #000000;\">\ud83d\udcde \u0e2b\u0e23\u0e37\u0e2d<span style=\"color: #ff0000;\">\u0e42\u0e17\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32<\/span> : <span style=\"font-weight: 400;\"><a href=\"tel:061-051-6661\">061 051 6661<\/a><\/span><\/span><\/p><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-23650\" src=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-300x300.webp\" alt=\"add line@ douglas business school\" width=\"42\" height=\"42\" srcset=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-300x300.webp 300w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-150x150.webp 150w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-12x12.webp 12w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-50x50.webp 50w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school.webp 320w\" sizes=\"(max-width: 42px) 100vw, 42px\" \/>\u00a0: <a href=\"https:\/\/lin.ee\/fxAjqio\" target=\"_blank\" rel=\"noopener\">@douglasth<\/a><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/qr-official.line.me\/gs\/M_381lmmli_BW.png?oat_content=qr\" width=\"98\" height=\"98\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-72bd397 elementor-hidden-desktop elementor-hidden-tablet elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"72bd397\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1c6a4c6\" data-id=\"1c6a4c6\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e0e1ff1 elementor-widget elementor-widget-text-editor\" data-id=\"e0e1ff1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><strong>\u0e15\u0e49\u0e2d\u0e07\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 <\/strong><strong>\u0e2b\u0e23\u0e37\u0e2d <br \/>\u0e21\u0e35\u0e04\u0e33\u0e16\u0e32\u0e21\u0e2d\u0e37\u0e48\u0e19\u0e46<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-df5aec4 elementor-widget elementor-widget-text-editor\" data-id=\"df5aec4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><span style=\"font-weight: 400;\">\u0e2d\u0e35\u0e40\u0e21\u0e25\u0e21\u0e32\u0e2a\u0e2d\u0e1a\u0e16\u0e32\u0e21\u0e40\u0e23\u0e32<\/span><b> \u0e1f\u0e23\u0e35 <\/b><span style=\"font-weight: 400;\">\u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e04\u0e2d\u0e23\u0e4c\u0e2a\u0e40\u0e23\u0e35\u0e22\u0e19\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\u0e08\u0e32\u0e01\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29\u0e41\u0e25\u0e30\u0e2d\u0e40\u0e21\u0e23\u0e34\u0e01\u0e32<\/span><\/p><p style=\"text-align: center;\"><b>\ud83d\udcde <\/b><span style=\"font-weight: 400;\">\u0e2b\u0e23\u0e37\u0e2d<\/span><span style=\"font-weight: 400; color: #ff0000;\">\u0e42\u0e17\u0e23\u0e1b\u0e23\u0e36\u0e01\u0e29\u0e32<\/span><span style=\"font-weight: 400;\"> : <a href=\"tel:061-051-6661\">061 051 6661<\/a><\/span><\/p><p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-23650\" src=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-300x300.webp\" alt=\"add line@ douglas business school\" width=\"42\" height=\"42\" srcset=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-300x300.webp 300w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-150x150.webp 150w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-12x12.webp 12w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school-50x50.webp 50w, https:\/\/www.douglas.co.th\/wp-content\/uploads\/2024\/04\/add-line-douglas-business-school.webp 320w\" sizes=\"(max-width: 42px) 100vw, 42px\" \/>\u00a0: <a href=\"https:\/\/lin.ee\/fxAjqio\" target=\"_blank\" rel=\"noopener\">@douglasth<\/a><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter\" src=\"https:\/\/qr-official.line.me\/gs\/M_381lmmli_BW.png?oat_content=qr\" width=\"98\" height=\"98\" \/><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-13fc12e5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"13fc12e5\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b940577\" data-id=\"b940577\" data-element_type=\"column\" data-e-type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f07ce92 elementor-button-align-stretch elementor-widget elementor-widget-form\" data-id=\"f07ce92\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;step_next_label&quot;:&quot;Next&quot;,&quot;step_previous_label&quot;:&quot;Previous&quot;,&quot;button_width&quot;:&quot;100&quot;,&quot;step_type&quot;:&quot;number_text&quot;,&quot;step_icon_shape&quot;:&quot;circle&quot;}\" data-widget_type=\"form.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<form class=\"elementor-form\" method=\"post\" name=\"New Form\">\n\t\t\t<input type=\"hidden\" name=\"post_id\" value=\"13259\"\/>\n\t\t\t<input type=\"hidden\" name=\"form_id\" value=\"f07ce92\"\/>\n\t\t\t<input type=\"hidden\" name=\"referer_title\" value=\"Douglas Business School (Thailand)\" \/>\n\n\t\t\t\n\t\t\t<div class=\"elementor-form-fields-wrapper elementor-labels-above\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-name elementor-col-100\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[name]\" id=\"form-field-name\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"\u0e0a\u0e37\u0e48\u0e2d-\u0e2a\u0e01\u0e38\u0e25\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-email elementor-field-group elementor-column elementor-field-group-email elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"email\" name=\"form_fields[email]\" id=\"form-field-email\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"\u0e2d\u0e35\u0e40\u0e21\u0e25\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-text elementor-field-group elementor-column elementor-field-group-field_85863fa elementor-col-100 elementor-field-required\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<input size=\"1\" type=\"text\" name=\"form_fields[field_85863fa]\" id=\"form-field-field_85863fa\" class=\"elementor-field elementor-size-sm  elementor-field-textual\" placeholder=\"\u0e40\u0e1a\u0e2d\u0e23\u0e4c\u0e42\u0e17\u0e23\" required=\"required\" aria-required=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-textarea elementor-field-group elementor-column elementor-field-group-message elementor-col-100\">\n\t\t\t\t\t<textarea class=\"elementor-field-textual elementor-field  elementor-size-sm\" name=\"form_fields[message]\" id=\"form-field-message\" rows=\"4\" placeholder=\"\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e16\u0e36\u0e07\u0e40\u0e23\u0e32...\"><\/textarea>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-type-recaptcha elementor-field-group elementor-column elementor-field-group-field_26a949e elementor-col-100\">\n\t\t\t\t\t<div class=\"elementor-field\" id=\"form-field-field_26a949e\"><div class=\"elementor-g-recaptcha\" data-sitekey=\"6LdyZz4pAAAAACu6TxUqDR-GGGuBn8AGskITqsWz\" data-type=\"v2_checkbox\" data-theme=\"light\" data-size=\"normal\"><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<div class=\"elementor-field-group elementor-column elementor-field-type-submit elementor-col-100 e-form__buttons\">\n\t\t\t\t\t<button type=\"submit\" class=\"elementor-button elementor-size-sm\">\n\t\t\t\t\t\t<span >\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\" elementor-button-icon\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\u0e2a\u0e48\u0e07\u0e02\u0e49\u0e2d\u0e04\u0e27\u0e32\u0e21<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/button>\n\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t<\/form>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ac6de elementor-widget elementor-widget-spacer\" data-id=\"45ac6de\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e1731b5 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e1731b5\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ee51a33\" data-id=\"ee51a33\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-db9fe5a elementor-widget elementor-widget-spacer\" data-id=\"db9fe5a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9c2a96f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9c2a96f\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<main class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-80e8098\" data-id=\"80e8098\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9917aa7 elementor-widget elementor-widget-heading\" data-id=\"9917aa7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\"><p style=\"font-size:25px\">\u0e04\u0e33\u0e16\u0e32\u0e21\u0e17\u0e35\u0e48\u0e1e\u0e1a\u0e1a\u0e48\u0e2d\u0e22<\/span><\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-77ca4d9 elementor-widget elementor-widget-accordion\" data-id=\"77ca4d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion\">\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1251\" class=\"elementor-tab-title\" data-tab=\"1\" role=\"button\" aria-controls=\"elementor-tab-content-1251\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e44\u0e23<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1251\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"1\" role=\"region\" aria-labelledby=\"elementor-tab-title-1251\"><p class=\"p1\"><span class=\"s1\">\u0e17\u0e32\u0e07\u0e40\u0e23\u0e32\u0e08\u0e30\u0e2a\u0e48\u0e07\u0e41\u0e1a\u0e1a\u0e1f\u0e2d\u0e23\u0e4c\u0e21\u0e43\u0e2b\u0e49\u0e01\u0e23\u0e2d\u0e01\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e41\u0e25\u0e30\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e22\u0e37\u0e48\u0e19\u0e43\u0e1a\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e1c\u0e48\u0e32\u0e19\u0e0a\u0e48\u0e2d\u0e07\u0e17\u0e32\u0e07\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c (<a href=\"mailto:info@douglas.co.th\" target=\"_blank\" rel=\"noopener\">\u0e2d\u0e35\u0e40\u0e21\u0e25<\/a> \u0e2b\u0e23\u0e37\u0e2d <a href=\"https:\/\/lin.ee\/fxAjqio\" target=\"_blank\" rel=\"noopener\">LINE@<\/a>) \u0e2b\u0e23\u0e37\u0e2d \u0e19\u0e31\u0e14\u0e22\u0e37\u0e48\u0e19\u0e40\u0e2d\u0e01\u0e2a\u0e32\u0e23\u0e01\u0e31\u0e1a\u0e40\u0e08\u0e49\u0e32\u0e2b\u0e19\u0e49\u0e32\u0e17\u0e35\u0e48\u0e17\u0e35\u0e48\u0e2d\u0e2d\u0e1f\u0e1f\u0e34\u0e28 (\u0e42\u0e17\u0e23\u0e19\u0e31\u0e14 <span style=\"font-weight: 400;\"><a href=\"tel:061-051-6661\">061 051 6661<\/a><\/span>)<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1252\" class=\"elementor-tab-title\" data-tab=\"2\" role=\"button\" aria-controls=\"elementor-tab-content-1252\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u0e04\u0e48\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e01\u0e35\u0e48\u0e1a\u0e32\u0e17?<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1252\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"2\" role=\"region\" aria-labelledby=\"elementor-tab-title-1252\"><p><span style=\"font-weight: 400;\">\u0e04\u0e48\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e21\u0e35\u0e01\u0e32\u0e23\u0e41\u0e1b\u0e23\u0e1c\u0e31\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e15\u0e25\u0e2d\u0e14\u0e40\u0e27\u0e25\u0e32 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e17\u0e23\u0e32\u0e1a\u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e41\u0e2d\u0e14 LINE : <a href=\"https:\/\/lin.ee\/fxAjqio\" target=\"_blank\" rel=\"noopener\">@douglasth<\/a> | \u0e2d\u0e35\u0e40\u0e21\u0e25 <\/span><a href=\"mailto:info@douglas.co.th\"><span style=\"font-weight: 400;\">info@douglas.co.th<\/span><\/a> \u0e2b\u0e23\u0e37\u0e2d\u0e42\u0e17\u0e23<span style=\"font-weight: 400;\">\u00a0<a href=\"tel:064-545-0061\">064-545-0061<\/a><\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1253\" class=\"elementor-tab-title\" data-tab=\"3\" role=\"button\" aria-controls=\"elementor-tab-content-1253\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u0e43\u0e0a\u0e49\u0e40\u0e27\u0e25\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19\u0e19\u0e32\u0e19\u0e41\u0e04\u0e48\u0e44\u0e2b\u0e19<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1253\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"3\" role=\"region\" aria-labelledby=\"elementor-tab-title-1253\"><p><span style=\"font-weight: 400;\">\u0e20\u0e32\u0e22\u0e43\u0e19\u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32 1 \u0e1b\u0e35 \u0e2b\u0e23\u0e37\u0e2d\u0e19\u0e32\u0e19\u0e01\u0e27\u0e48\u0e32 (\u0e02\u0e36\u0e49\u0e19\u0e2d\u0e22\u0e39\u0e48\u0e01\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e2a\u0e48\u0e07\u0e07\u0e32\u0e19)<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1254\" class=\"elementor-tab-title\" data-tab=\"4\" role=\"button\" aria-controls=\"elementor-tab-content-1254\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e40\u0e02\u0e49\u0e32\u0e23\u0e48\u0e27\u0e21\u0e07\u0e32\u0e19\u0e23\u0e31\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e44\u0e14\u0e49\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1254\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"4\" role=\"region\" aria-labelledby=\"elementor-tab-title-1254\"><p><span style=\"font-weight: 400;\">\u0e44\u0e14\u0e49 \u0e41\u0e15\u0e48\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e41\u0e08\u0e49\u0e07\u0e01\u0e31\u0e1a\u0e17\u0e32\u0e07\u0e17\u0e35\u0e21\u0e25\u0e48\u0e27\u0e07\u0e2b\u0e19\u0e49\u0e32 (\u0e20\u0e32\u0e22\u0e43\u0e19\u0e40\u0e14\u0e37\u0e2d\u0e19\u0e21\u0e01\u0e23\u0e32\u0e04\u0e21) \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e04\u0e27\u0e32\u0e21\u0e2a\u0e30\u0e14\u0e27\u0e01\u0e43\u0e19\u0e01\u0e32\u0e23\u0e14\u0e33\u0e40\u0e19\u0e34\u0e19\u0e01\u0e32\u0e23 \u0e17\u0e31\u0e49\u0e07\u0e19\u0e35\u0e49 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e15\u0e49\u0e2d\u0e07\u0e2d\u0e2d\u0e01\u0e04\u0e48\u0e32\u0e43\u0e0a\u0e49\u0e08\u0e48\u0e32\u0e22\u0e2a\u0e33\u0e2b\u0e23\u0e31\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e14\u0e34\u0e19\u0e17\u0e32\u0e07\u0e41\u0e25\u0e30\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e40\u0e2d\u0e07 \u0e42\u0e14\u0e22\u0e40\u0e23\u0e32\u0e08\u0e30\u0e08\u0e2d\u0e07\u0e17\u0e35\u0e48\u0e1e\u0e31\u0e01\u0e41\u0e25\u0e30\u0e15\u0e31\u0e4b\u0e27\u0e40\u0e04\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e1a\u0e34\u0e19\u0e43\u0e2b\u0e49<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1255\" class=\"elementor-tab-title\" data-tab=\"5\" role=\"button\" aria-controls=\"elementor-tab-content-1255\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u0e15\u0e49\u0e2d\u0e07\u0e43\u0e0a\u0e49\u0e04\u0e30\u0e41\u0e19\u0e19 GPA \u0e43\u0e19\u0e01\u0e32\u0e23\u0e2a\u0e21\u0e31\u0e04\u0e23\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1255\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"5\" role=\"region\" aria-labelledby=\"elementor-tab-title-1255\"><p><span style=\"font-weight: 400;\">\u0e44\u0e21\u0e48\u0e08\u0e33\u0e40\u0e1b\u0e47\u0e19 \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e43\u0e0a\u0e49\u0e41\u0e04\u0e48\u0e1b\u0e23\u0e30\u0e2a\u0e1a\u0e01\u0e32\u0e23\u0e13\u0e4c\u0e17\u0e33\u0e07\u0e32\u0e19 1 \u0e1b\u0e35 \u0e41\u0e25\u0e30\u0e08\u0e1a\u0e08\u0e32\u0e01\u0e04\u0e13\u0e30\u0e2d\u0e30\u0e44\u0e23\u0e01\u0e47\u0e44\u0e14\u0e49<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1256\" class=\"elementor-tab-title\" data-tab=\"6\" role=\"button\" aria-controls=\"elementor-tab-content-1256\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1c\u0e48\u0e2d\u0e19\u0e08\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49\u0e44\u0e2b\u0e21<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1256\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"6\" role=\"region\" aria-labelledby=\"elementor-tab-title-1256\"><p><span style=\"font-weight: 400;\">\u0e44\u0e14\u0e49 \u0e2a\u0e32\u0e21\u0e32\u0e23\u0e16\u0e1c\u0e48\u0e2d\u0e19\u0e08\u0e48\u0e32\u0e22\u0e44\u0e14\u0e49 0% 10 \u0e40\u0e14\u0e37\u0e2d\u0e19<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1257\" class=\"elementor-tab-title\" data-tab=\"7\" role=\"button\" aria-controls=\"elementor-tab-content-1257\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e41\u0e1a\u0e1a\u0e40\u0e1b\u0e47\u0e19\u0e44\u0e1f\u0e25\u0e4c \u0e2b\u0e23\u0e37\u0e2d \u0e02\u0e2d\u0e07\u0e08\u0e23\u0e34\u0e07 \u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1257\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"7\" role=\"region\" aria-labelledby=\"elementor-tab-title-1257\"><p><span style=\"font-weight: 400;\">\u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e23\u0e31\u0e1a\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32\u0e02\u0e2d\u0e07\u0e08\u0e23\u0e34\u0e07 \u0e08\u0e32\u0e01\u0e21\u0e2b\u0e32\u0e27\u0e34\u0e17\u0e22\u0e32\u0e25\u0e31\u0e22 \u0e2a\u0e48\u0e07\u0e15\u0e23\u0e07\u0e16\u0e36\u0e07\u0e1a\u0e49\u0e32\u0e19\u0e02\u0e2d\u0e07\u0e04\u0e38\u0e13<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-accordion-item\">\n\t\t\t\t\t<div id=\"elementor-tab-title-1258\" class=\"elementor-tab-title\" data-tab=\"8\" role=\"button\" aria-controls=\"elementor-tab-content-1258\" aria-expanded=\"false\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon elementor-accordion-icon-left\" aria-hidden=\"true\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-closed\"><i class=\"fas fa-plus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t<span class=\"elementor-accordion-icon-opened\"><i class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-accordion-title\" tabindex=\"0\">\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a\u0e2b\u0e23\u0e37\u0e2d\u0e44\u0e21\u0e48<\/a>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t<div id=\"elementor-tab-content-1258\" class=\"elementor-tab-content elementor-clearfix\" data-tab=\"8\" role=\"region\" aria-labelledby=\"elementor-tab-title-1258\"><p><span style=\"font-weight: 400;\">\u0e44\u0e21\u0e48\u0e15\u0e49\u0e2d\u0e07\u0e17\u0e33\u0e02\u0e49\u0e2d\u0e2a\u0e2d\u0e1a \u0e2a\u0e48\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19<\/span><\/p><\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/main>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fb76a52 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fb76a52\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12c5b9f\" data-id=\"12c5b9f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1237da0 elementor-fixed elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"1237da0\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;fixed&quot;}\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"#scroll\">\n\t\t\t<i aria-hidden=\"true\" class=\"fas fa-arrow-alt-circle-up\"><\/i>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>L.L.B. (Hons) Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c \u0e23\u0e32\u0e22\u0e25\u0e30\u0e40\u0e2d\u0e35\u0e22\u0e14\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e23\u0e30\u0e22\u0e30\u0e40\u0e27\u0e25\u0e32\u0e40\u0e23\u0e35\u0e22\u0e19 1 \u0e1b\u0e35 \u0e0a\u0e48\u0e27\u0e07\u0e40\u0e27\u0e25\u0e32\u0e40\u0e1b\u0e34\u0e14\u0e40\u0e17\u0e2d\u0e21 \u0e21\u0e01\u0e23\u0e32\u0e04\u0e21 &amp; \u0e01\u0e31\u0e19\u0e22\u0e32\u0e22\u0e19 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 100% \u0e15\u0e32\u0e23\u0e32\u0e07\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e40\u0e23\u0e35\u0e22\u0e19\u0e40\u0e27\u0e25\u0e32\u0e44\u0e2b\u0e19\u0e01\u0e47\u0e44\u0e14\u0e49 Pathway to a Degree 2 \u0e2a\u0e48\u0e27\u0e19 \u0e23\u0e39\u0e1b\u0e41\u0e1a\u0e1a\u0e01\u0e32\u0e23\u0e1b\u0e23\u0e30\u0e40\u0e21\u0e34\u0e19 \u0e2a\u0e48\u0e07\u0e41\u0e15\u0e48\u0e01\u0e32\u0e23\u0e1a\u0e49\u0e32\u0e19 \u0e44\u0e21\u0e48\u0e21\u0e35\u0e01\u0e32\u0e23\u0e2a\u0e2d\u0e1a \u0e20\u0e32\u0e29\u0e32\u0e43\u0e19\u0e01\u0e32\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19 \u0e20\u0e32\u0e29\u0e32\u0e2d\u0e31\u0e07\u0e01\u0e24\u0e29 \u0e2a\u0e21\u0e31\u0e04\u0e23\u0e40\u0e23\u0e35\u0e22\u0e19! \u0e40\u0e01\u0e35\u0e48\u0e22\u0e27\u0e01\u0e31\u0e1a\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23\u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 (Hons) \u0e2a\u0e32\u0e02\u0e32 Law (top-up) \u0e08\u0e30\u0e43\u0e2b\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e14\u0e49\u0e32\u0e19\u0e27\u0e34\u0e40\u0e04\u0e23\u0e32\u0e30\u0e2b\u0e4c (Analytics) \u0e41\u0e25\u0e30 \u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e40\u0e09\u0e1e\u0e32\u0e30\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 (International Business Law) \u0e40\u0e21\u0e37\u0e48\u0e2d\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e1a \u0e19\u0e31\u0e01\u0e40\u0e23\u0e35\u0e22\u0e19\u0e08\u0e30\u0e44\u0e14\u0e49\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e15\u0e48\u0e32\u0e07\u0e46 \u0e14\u0e31\u0e07\u0e19\u0e35\u0e49 : \u2022 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e41\u0e25\u0e30\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e02\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e18\u0e38\u0e23\u0e01\u0e34\u0e08\u0e23\u0e30\u0e2b\u0e27\u0e48\u0e32\u0e07\u0e1b\u0e23\u0e30\u0e40\u0e17\u0e28 \u2022 \u0e1e\u0e31\u0e12\u0e19\u0e32\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e17\u0e32\u0e07\u0e14\u0e49\u0e32\u0e19\u0e01\u0e23\u0e2d\u0e1a\u0e17\u0e32\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22 \u0e40\u0e1e\u0e37\u0e48\u0e2d\u0e19\u0e33\u0e44\u0e1b\u0e1b\u0e23\u0e30\u0e22\u0e38\u0e01\u0e15\u0e4c\u0e43\u0e0a\u0e49\u0e43\u0e2b\u0e49\u0e40\u0e2b\u0e21\u0e32\u0e30\u0e01\u0e31\u0e1a\u0e2d\u0e38\u0e15\u0e2a\u0e32\u0e2b\u0e01\u0e23\u0e23\u0e21\u0e41\u0e15\u0e48\u0e25\u0e30\u0e1b\u0e23\u0e30\u0e40\u0e20\u0e17 \u2022 \u0e21\u0e35\u0e04\u0e27\u0e32\u0e21\u0e40\u0e02\u0e49\u0e32\u0e43\u0e08\u0e2d\u0e22\u0e48\u0e32\u0e07\u0e16\u0e48\u0e2d\u0e07\u0e41\u0e17\u0e49\u0e43\u0e19\u0e40\u0e23\u0e37\u0e48\u0e2d\u0e07\u0e01\u0e0e\u0e2b\u0e21\u0e32\u0e22\u0e2b\u0e25\u0e32\u0e22\u0e41\u0e02\u0e19\u0e07 \u0e40\u0e0a\u0e48\u0e19 \u2022<\/p>","protected":false},"author":1,"featured_media":12080,"parent":11623,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-13259","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L.L.B. (Hons) Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c<\/title>\n<meta name=\"description\" content=\"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b.\u0e15\u0e23\u0e35 L.L.B. \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e32\u0e02\u0e32 Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 100% \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32 \u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e23\u0e34\u0e07\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L.L.B. (Hons) Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\" \/>\n<meta property=\"og:description\" content=\"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b.\u0e15\u0e23\u0e35 L.L.B. \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e32\u0e02\u0e32 Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 100% \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32 \u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e23\u0e34\u0e07\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/\" \/>\n<meta property=\"og:site_name\" content=\"Douglas Business School (Thailand)\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/douglas.thailand\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-11T03:11:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2023\/12\/dbs-thailand-logo.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"480\" \/>\n\t<meta property=\"og:image:height\" content=\"480\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/llb-hons-law-uclan-th\\\/\",\"url\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/llb-hons-law-uclan-th\\\/\",\"name\":\"L.L.B. (Hons) Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/llb-hons-law-uclan-th\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/llb-hons-law-uclan-th\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.douglas.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/dbs-thailand-logo.webp\",\"datePublished\":\"2023-11-30T03:53:04+00:00\",\"dateModified\":\"2026-04-11T03:11:14+00:00\",\"description\":\"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b.\u0e15\u0e23\u0e35 L.L.B. \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e32\u0e02\u0e32 Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 100% \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32 \u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e23\u0e34\u0e07\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/llb-hons-law-uclan-th\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/llb-hons-law-uclan-th\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/llb-hons-law-uclan-th\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.douglas.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/dbs-thailand-logo.webp\",\"contentUrl\":\"https:\\\/\\\/www.douglas.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/dbs-thailand-logo.webp\",\"width\":480,\"height\":480,\"caption\":\"\u0e42\u0e25\u0e42\u0e01\u0e49 DBS Thailand\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/llb-hons-law-uclan-th\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b.\u0e15\u0e23\u0e35\",\"item\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/undergraduate-dbs-th\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L.L.B. (Hons) \u0e2a\u0e32\u0e02\u0e32 Law\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/\",\"name\":\"Douglas Business School (Thailand)\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/#organization\"},\"alternateName\":\"DBS Thailand\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/#organization\",\"name\":\"Douglas Business School (Thailand)\",\"alternateName\":\"DBS Thailand\",\"url\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.douglas.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/dbs-thailand-logo.webp\",\"contentUrl\":\"https:\\\/\\\/www.douglas.co.th\\\/wp-content\\\/uploads\\\/2023\\\/12\\\/dbs-thailand-logo.webp\",\"width\":480,\"height\":480,\"caption\":\"Douglas Business School (Thailand)\"},\"image\":{\"@id\":\"https:\\\/\\\/www.douglas.co.th\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/douglas.thailand\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L.L.B. (Hons) Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","description":"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b.\u0e15\u0e23\u0e35 L.L.B. \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e32\u0e02\u0e32 Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 100% \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32 \u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e23\u0e34\u0e07","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/","og_locale":"th_TH","og_type":"article","og_title":"L.L.B. (Hons) Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","og_description":"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b.\u0e15\u0e23\u0e35 L.L.B. \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e32\u0e02\u0e32 Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 100% \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32 \u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e23\u0e34\u0e07","og_url":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/","og_site_name":"Douglas Business School (Thailand)","article_publisher":"https:\/\/www.facebook.com\/douglas.thailand","article_modified_time":"2026-04-11T03:11:14+00:00","og_image":[{"width":480,"height":480,"url":"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2023\/12\/dbs-thailand-logo.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"5 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/","url":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/","name":"L.L.B. (Hons) Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c","isPartOf":{"@id":"https:\/\/www.douglas.co.th\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/#primaryimage"},"image":{"@id":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/#primaryimage"},"thumbnailUrl":"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2023\/12\/dbs-thailand-logo.webp","datePublished":"2023-11-30T03:53:04+00:00","dateModified":"2026-04-11T03:11:14+00:00","description":"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b.\u0e15\u0e23\u0e35 L.L.B. \u0e40\u0e01\u0e35\u0e22\u0e23\u0e15\u0e34\u0e19\u0e34\u0e22\u0e21 \u0e2a\u0e32\u0e02\u0e32 Law \u0e2d\u0e2d\u0e19\u0e44\u0e25\u0e19\u0e4c 100% \u0e1e\u0e23\u0e49\u0e2d\u0e21\u0e43\u0e1a\u0e1b\u0e23\u0e34\u0e0d\u0e0d\u0e32 \u0e19\u0e33\u0e04\u0e27\u0e32\u0e21\u0e23\u0e39\u0e49\u0e43\u0e0a\u0e49\u0e44\u0e14\u0e49\u0e43\u0e19\u0e0a\u0e35\u0e27\u0e34\u0e15\u0e08\u0e23\u0e34\u0e07","breadcrumb":{"@id":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/#primaryimage","url":"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2023\/12\/dbs-thailand-logo.webp","contentUrl":"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2023\/12\/dbs-thailand-logo.webp","width":480,"height":480,"caption":"\u0e42\u0e25\u0e42\u0e01\u0e49 DBS Thailand"},{"@type":"BreadcrumbList","@id":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/llb-hons-law-uclan-th\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.douglas.co.th\/th\/"},{"@type":"ListItem","position":2,"name":"\u0e2b\u0e25\u0e31\u0e01\u0e2a\u0e39\u0e15\u0e23 \u0e1b.\u0e15\u0e23\u0e35","item":"https:\/\/www.douglas.co.th\/th\/undergraduate-dbs-th\/"},{"@type":"ListItem","position":3,"name":"L.L.B. (Hons) \u0e2a\u0e32\u0e02\u0e32 Law"}]},{"@type":"WebSite","@id":"https:\/\/www.douglas.co.th\/th\/#website","url":"https:\/\/www.douglas.co.th\/th\/","name":"Douglas Business School (Thailand)","description":"","publisher":{"@id":"https:\/\/www.douglas.co.th\/th\/#organization"},"alternateName":"DBS Thailand","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.douglas.co.th\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/www.douglas.co.th\/th\/#organization","name":"Douglas Business School (Thailand)","alternateName":"DBS Thailand","url":"https:\/\/www.douglas.co.th\/th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/www.douglas.co.th\/th\/#\/schema\/logo\/image\/","url":"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2023\/12\/dbs-thailand-logo.webp","contentUrl":"https:\/\/www.douglas.co.th\/wp-content\/uploads\/2023\/12\/dbs-thailand-logo.webp","width":480,"height":480,"caption":"Douglas Business School (Thailand)"},"image":{"@id":"https:\/\/www.douglas.co.th\/th\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/douglas.thailand"]}]}},"_links":{"self":[{"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/pages\/13259","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/comments?post=13259"}],"version-history":[{"count":359,"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/pages\/13259\/revisions"}],"predecessor-version":[{"id":48372,"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/pages\/13259\/revisions\/48372"}],"up":[{"embeddable":true,"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/pages\/11623"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/media\/12080"}],"wp:attachment":[{"href":"https:\/\/www.douglas.co.th\/th\/wp-json\/wp\/v2\/media?parent=13259"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}